{"id":1969,"date":"2024-01-19T11:52:21","date_gmt":"2024-01-19T11:52:21","guid":{"rendered":"https:\/\/legalbrandservices.com\/2024\/01\/19\/que-aixequi-la-ma-qui\/"},"modified":"2024-01-19T11:56:54","modified_gmt":"2024-01-19T11:56:54","slug":"que-aixequi-la-ma-qui","status":"publish","type":"post","link":"https:\/\/legalbrandservices.com\/ca\/2024\/01\/19\/que-aixequi-la-ma-qui\/","title":{"rendered":"que aixequi la m\u00e0 qui&#8230;"},"content":{"rendered":"\n<p>Que aixequi la m\u00e0 qui aquestes vacances s\u2019hagi aturat a mirar a una parada del mercat o del passeig de la platja plena de productes &#8220;de marca&#8221;.<\/p>\n\n<p>Que aixequi la m\u00e0 qui s\u2019hagi comprat una motxilla, unes ulleres, unes sabatilles o una samarreta &#8220;de marca&#8221; a aquestes parades.<\/p>\n\n<p>Malauradament la venda de productes falsificats va en augment i \u00e9s una forta amena\u00e7a per al desenvolupament i innovaci\u00f3 de les empreses. Est\u00e0 clar que s\u00f3n productes que atrauen cada vegada m\u00e9s al p\u00fablic i sobretot als joves que no tenen un pressupost de 120 euros per gastar-se en unes sabatilles per\u00f2 si 20 euros per unes &#8220;quasi id\u00e8ntiques&#8221;.<\/p>\n\n<p>El percentatge d\u2019espanyols entre 15 i 24 anys que han comprat un producte falsificat de forma intencionada s\u2019ha triplicat segons dades disponibles, passant del 16% l\u2019any 2019 al 45% al 2021. Precisament per tal de donar-li visibilitat a aquest problema la Oficina Espa\u00f1ola de Patentes y Marcas (OEPM) junt amb la Asociaci\u00f3n para la Defensa de la Marca (Andema) van posar en marxa l\u2019any passat una campanya de v\u00eddeos a les xarxes socials, per a que el jovent prengui consci\u00e8ncia.<\/p>\n\n<p>Aquesta campanya consistia en reels basats en la compra de productes amb m\u00e9s demanda entre els joves: roba, cal\u00e7at, cosm\u00e8tics i aparells electr\u00f2nics. Quatre hist\u00f2ries on es demostrava la defici\u00e8ncia dels productes falsificats perqu\u00e8, naturalment, no passen cap control de qualitat ni de seguretat. M\u00e9s greu \u00e9s el cas de la compra de cosm\u00e8tics i de les ulleres de sol perqu\u00e8 poden posar en risc la salut dels compradors.<\/p>\n\n<p>Encara que una fam\u00edlia compri nom\u00e9s un producte falsificat, ha de saber que provoca unes p\u00e8rdues anuals de 2.200 milions d\u2019euros a diferents sectors econ\u00f2mics. Principalment perqu\u00e8 els venedors ambulants il\u00b7legals no paguen cap tipus d\u2019impostos, no tenen permisos, no paguen lloguers i perjudiquen al comer\u00e7 local eliminant llocs de feina.<\/p>\n\n<p>S\u2019ha de canviar aquest tipus de mentalitat i ensenyar als joves que la compra de falsificacions no \u00e9s la soluci\u00f3 i no est\u00e0 tampoc justificada quan el preu del producte original \u00e9s molt elevat. Els hem de fer veure que hi ha alternatives al mercat com altres productes de marca per\u00f2 a preus m\u00e9s assequibles i accessibles per a totes les butxaques.<\/p>\n\n<p><\/p>\n\n<p><em>Pened\u00e8s Econ\u00f2mic &#8211; Setembre 2023<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00fanica manera d&#8217;acabar amb els productes falsificats \u00e9s&#8230; no comprant!<\/p>\n","protected":false},"author":2,"featured_media":1967,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[64,72,88],"tags":[65,56,55],"dipi_cpt_category":[],"_links":{"self":[{"href":"https:\/\/legalbrandservices.com\/ca\/wp-json\/wp\/v2\/posts\/1969"}],"collection":[{"href":"https:\/\/legalbrandservices.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legalbrandservices.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legalbrandservices.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/legalbrandservices.com\/ca\/wp-json\/wp\/v2\/comments?post=1969"}],"version-history":[{"count":1,"href":"https:\/\/legalbrandservices.com\/ca\/wp-json\/wp\/v2\/posts\/1969\/revisions"}],"predecessor-version":[{"id":1970,"href":"https:\/\/legalbrandservices.com\/ca\/wp-json\/wp\/v2\/posts\/1969\/revisions\/1970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legalbrandservices.com\/ca\/wp-json\/wp\/v2\/media\/1967"}],"wp:attachment":[{"href":"https:\/\/legalbrandservices.com\/ca\/wp-json\/wp\/v2\/media?parent=1969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legalbrandservices.com\/ca\/wp-json\/wp\/v2\/categories?post=1969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legalbrandservices.com\/ca\/wp-json\/wp\/v2\/tags?post=1969"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/legalbrandservices.com\/ca\/wp-json\/wp\/v2\/dipi_cpt_category?post=1969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}